{"id":1197,"date":"2021-10-13T11:02:34","date_gmt":"2021-10-13T14:02:34","guid":{"rendered":"http:\/\/treinamentolivre.com\/aluno01\/?p=1197"},"modified":"2021-10-13T11:04:13","modified_gmt":"2021-10-13T14:04:13","slug":"ia-na-fiocruz","status":"publish","type":"post","link":"https:\/\/treinamentolivre.com\/aluno01\/arquivos\/1197","title":{"rendered":"IA na Fiocruz"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote\"><p>Compilei v\u00eddeos da Fiocruz que abordam os usos da IA na sa\u00fade. Divirtam-se !<\/p><\/blockquote>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Intelig\u00eancia Artificial: a nova fronteira da ci\u00eancia brasileira\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/HAYa6RtkdlA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Intelig\u00eancia Artificial: a nova fronteira da ci\u00eancia brasileira.<\/p>\n\n\n\n<ul><li>A Fiocruz Bahia participou da 17\u00aa edi\u00e7\u00e3o da Semana Nacional de Ci\u00eancia e Tecnologia, que esse ano tem como tema \u201cIntelig\u00eancia Artificial: a nova fronteira da ci\u00eancia brasileira\u201d. Na tarde do dia 21\/10, a tem\u00e1tica foi sobre \u201cA utiliza\u00e7\u00e3o da Intelig\u00eancia Artificial e tomada de decis\u00f5es sobre a pandemia no Brasil\u201d, em que pesquisadores apresentaram suas atividades relacionadas ao emprego de Intelig\u00eancia Artificial para Covid-19.<\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Tocando a Real - Intelig\u00eancia Artificial\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/weK7sC8dYkk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><figcaption>Tocando a Real &#8211; Intelig\u00eancia Artificial<\/figcaption><\/figure>\n\n\n\n<ul><li>Intelig\u00eancia Artificial: o Tocando Real explica nesse epis\u00f3dio o que \u00e9 intelig\u00eancia artificial (I.A). Teria a ver com androides como os de Blade Runner ou Exterminador do Futuro? Intelig\u00eancia Artificial. Onde vive? Como se reproduz? Do que se alimenta? Para ficar por dentro do que \u00e9 intelig\u00eancia artificial de verdade, como foi desenvolvida, quais seus usos, entre muitas outras coisas.<\/li><\/ul>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Compilei v\u00eddeos da Fiocruz que abordam os usos da IA na sa\u00fade. Divirtam-se ! Intelig\u00eancia Artificial: a nova fronteira da ci\u00eancia brasileira. A Fiocruz Bahia participou da 17\u00aa edi\u00e7\u00e3o da&#8230;<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/treinamentolivre.com\/aluno01\/arquivos\/1197\">Continuar a ler&#8230;<span class=\"screen-reader-text\">IA na Fiocruz<\/span><\/a><\/div>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,78],"tags":[],"_links":{"self":[{"href":"https:\/\/treinamentolivre.com\/aluno01\/wp-json\/wp\/v2\/posts\/1197"}],"collection":[{"href":"https:\/\/treinamentolivre.com\/aluno01\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/treinamentolivre.com\/aluno01\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/treinamentolivre.com\/aluno01\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/treinamentolivre.com\/aluno01\/wp-json\/wp\/v2\/comments?post=1197"}],"version-history":[{"count":3,"href":"https:\/\/treinamentolivre.com\/aluno01\/wp-json\/wp\/v2\/posts\/1197\/revisions"}],"predecessor-version":[{"id":1200,"href":"https:\/\/treinamentolivre.com\/aluno01\/wp-json\/wp\/v2\/posts\/1197\/revisions\/1200"}],"wp:attachment":[{"href":"https:\/\/treinamentolivre.com\/aluno01\/wp-json\/wp\/v2\/media?parent=1197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/treinamentolivre.com\/aluno01\/wp-json\/wp\/v2\/categories?post=1197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/treinamentolivre.com\/aluno01\/wp-json\/wp\/v2\/tags?post=1197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}